{"id":1000636,"date":"2025-03-20T07:03:24","date_gmt":"2025-03-20T07:03:24","guid":{"rendered":"https:\/\/janubottle.com\/kontakt\/"},"modified":"2026-05-20T18:54:58","modified_gmt":"2026-05-20T18:54:58","slug":"contact","status":"publish","type":"page","link":"https:\/\/janubottle.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1000636\" class=\"elementor elementor-1000636 elementor-534\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73bb7f30 e-flex e-con-boxed glozin-responsive-column glozin-tablet-column--default glozin-responsive-column glozin-mobile-column--default glozin-responsive-column glozin-motion--var(--position) e-con e-parent\" data-id=\"73bb7f30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-224e8905 e-con-full e-flex glozin-responsive-column glozin-tablet-column--default glozin-responsive-column glozin-mobile-column--default glozin-responsive-column glozin-motion--var(--position) e-con e-child\" data-id=\"224e8905\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1953bb69 elementor-widget elementor-widget-glozin-heading\" data-id=\"1953bb69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<h3 class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tJanu Bottle O\u00dc\t\t\t\t<\/h3>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e30441 elementor-widget elementor-widget-glozin-heading\" data-id=\"35e30441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<div class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tReg: 17447389\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43091db3 elementor-widget elementor-widget-glozin-heading\" data-id=\"43091db3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<h5 class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tSupport:\t\t\t\t<\/h5>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d65f0 elementor-widget elementor-widget-glozin-heading\" data-id=\"b3d65f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<div class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tPhone: +372 54 501103<br \/>\nE-mail: info@janubottle.com\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c4b02 elementor-widget elementor-widget-glozin-heading\" data-id=\"73c4b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<h5 class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tBusiness client:\t\t\t\t<\/h5>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ce483bf elementor-widget elementor-widget-glozin-heading\" data-id=\"7ce483bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<div class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tinfo@janubottle.com\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643c8143 elementor-widget elementor-widget-glozin-heading\" data-id=\"643c8143\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<h5 class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tResellers:\t\t\t\t<\/h5>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26b7a21b elementor-widget elementor-widget-glozin-heading\" data-id=\"26b7a21b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<div class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tTallinn:<br>\nLEVI Design. Estonia pst. 9, Tallinn, Solaris Keskus 1. floor<br><br>\nP\u00e4rnu:<br>\nSONNE Kohv.Kodu.Kunst. Kuninga 34, P\u00e4rnu\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18f0b61e e-con-full e-flex glozin-responsive-column glozin-tablet-column--default glozin-responsive-column glozin-mobile-column--default glozin-responsive-column glozin-motion--var(--position) e-con e-child\" data-id=\"18f0b61e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad7058 elementor-widget elementor-widget-glozin-heading\" data-id=\"2ad7058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-heading-elementor\">\n\t\t\t\t<h3 class=\"glozin-heading d-flex align-items-center my-0 glozin-heading--default\">\n\t\t\t\t\tContact us\t\t\t\t<\/h3>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa3fd67 elementor-widget elementor-widget-glozin-contact-form\" data-id=\"5aa3fd67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glozin-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"glozin-contact-form\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1000635-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1000635\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1000636#wpcf7-f1000635-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1000635\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1000635-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"contact-form-row d-flex flex-wrap flex-nowrap-md gap-20 mb-20\">\n\t<div class=\"wpcf7-form-row position-relative w-100\">\n\t\t<p><label for=\"username\">Name<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"username\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"username\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"wpcf7-form-row position-relative w-100\">\n\t\t<p><label for=\"email\">E-mail<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"contact-form-row wpcf7-form-row position-relative w-100 mb-20\">\n\t<p><label for=\"message\">Text<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div class=\"contact-form-row mb-30\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I read and agree to <a href=\"https:\/\/janubottle.com\/en\/privacy-policy\/\">privacy policy<\/a>.<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div class=\"contact-form-row\">\n\t<p><button type=\"submit\" class=\"wpcf7-form-control wpcf7-submit has-spinner\">Send<\/button>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Janu Bottle O\u00dc Reg: 17447389 Support: Phone: +372 54 501103 E-mail: info@janubottle.com Business client: info@janubottle.com Resellers: Tallinn: LEVI Design. Estonia pst. 9, Tallinn, Solaris Keskus 1. floor P\u00e4rnu: SONNE Kohv.Kodu.Kunst. Kuninga 34, P\u00e4rnu Contact us Name E-mail Text I read and agree to privacy policy. Send<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1000636","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/pages\/1000636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/comments?post=1000636"}],"version-history":[{"count":4,"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/pages\/1000636\/revisions"}],"predecessor-version":[{"id":1000641,"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/pages\/1000636\/revisions\/1000641"}],"wp:attachment":[{"href":"https:\/\/janubottle.com\/en\/wp-json\/wp\/v2\/media?parent=1000636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}